{"id":3151,"date":"2022-02-03T12:10:03","date_gmt":"2022-02-03T17:10:03","guid":{"rendered":"https:\/\/runner-theme-116.flywheelsites.com\/?page_id=3151"},"modified":"2024-10-03T12:49:30","modified_gmt":"2024-10-03T17:49:30","slug":"terms-of-use","status":"publish","type":"page","link":"https:\/\/caribbeanbariatric.com\/es\/terms-of-use\/","title":{"rendered":"Condiciones de uso"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3151\" class=\"elementor elementor-3151\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ac7bc3f elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"6ac7bc3f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d3ab7eb\" data-id=\"7d3ab7eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60a0e068 elementor-widget elementor-widget-heading\" data-id=\"60a0e068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Condiciones de uso del sitio web<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae3551a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae3551a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;mountains&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1790e58\" data-id=\"1790e58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1493db5 elementor-widget elementor-widget-text-editor\" data-id=\"1493db5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El sitio web del Instituto Bari\u00e1trico del Caribe ubicado en caribbeanbariatric.com es un trabajo protegido por derechos de autor que pertenece al Instituto Bari\u00e1trico del Caribe. Ciertas caracter\u00edsticas del sitio pueden estar sujetas a directrices, t\u00e9rminos o reglas adicionales, que se publicar\u00e1n en el sitio en relaci\u00f3n con dichas caracter\u00edsticas.<\/p>\n<p>Todas estas condiciones, directrices y normas adicionales se incorporan por referencia a las presentes Condiciones.<\/p>\n<p>Estas Condiciones de Uso describen los t\u00e9rminos y condiciones legalmente vinculantes que supervisan su uso del Sitio. AL INICIAR SESI\u00d3N EN EL SITIO, USTED EST\u00c1 CUMPLIENDO CON ESTAS CONDICIONES y declara que tiene la autoridad y capacidad para aceptarlas. USTED DEBE TENER AL MENOS 18 A\u00d1OS DE EDAD PARA ACCEDER AL SITIO. SI NO EST\u00c1 DE ACUERDO CON TODAS LAS DISPOSICIONES DE ESTAS CONDICIONES, NO ACCEDA AL SITIO NI LO UTILICE.<\/p>\n<p>Estos t\u00e9rminos requieren el uso de la Secci\u00f3n 10.2 de arbitraje de forma individual para resolver disputas y tambi\u00e9n limitan los recursos disponibles para usted en caso de disputa. Estas condiciones de uso se crearon con la ayuda del generador de condiciones de uso.<\/p>\n<h2>Acceso al sitio<\/h2>\n<p>Sujeto a estas Condiciones. La Empresa le concede una licencia no transferible, no exclusiva, revocable y limitada para acceder al Sitio \u00fanicamente para su uso personal y no comercial.<\/p>\n<p>Ciertas restricciones. Los derechos aprobados para usted en estas Condiciones est\u00e1n sujetos a las siguientes restricciones: (a) no podr\u00e1 vender, alquilar, arrendar, transferir, ceder, distribuir, alojar o explotar comercialmente de cualquier otro modo el Sitio; (b) no podr\u00e1 modificar, realizar trabajos derivados, desensamblar, compilar a la inversa o aplicar ingenier\u00eda inversa a ninguna parte del Sitio; (c) no podr\u00e1 acceder al Sitio con el fin de crear un sitio web similar o de la competencia; y (d) salvo que se indique expresamente lo contrario, ninguna parte del Sitio podr\u00e1 copiarse, reproducirse, distribuirse, volver a publicarse, descargarse, mostrarse, enviarse por correo o transmitirse de ninguna forma ni por ning\u00fan medio, a menos que se indique lo contrario; toda futura versi\u00f3n, actualizaci\u00f3n u otra adici\u00f3n a la funcionalidad del Sitio estar\u00e1 sujeta a las presentes Condiciones. Todos los derechos de autor y otros avisos de propiedad del Sitio deber\u00e1n conservarse en todas las copias del mismo.<\/p>\n<p>La Empresa se reserva el derecho de cambiar, suspender o cesar el Sitio con o sin previo aviso. Usted aprueba que la Empresa no ser\u00e1 responsable ante usted ni ante terceros por ning\u00fan cambio, interrupci\u00f3n o cese del Sitio o de cualquier parte del mismo.<\/p>\n<p>Sin asistencia ni mantenimiento. Usted acepta que la Empresa no tendr\u00e1 obligaci\u00f3n alguna de prestarle asistencia en relaci\u00f3n con el Sitio.<\/p>\n<p>Excluyendo cualquier Contenido de Usuario que usted pueda proporcionar, usted es consciente de que todos los derechos de propiedad intelectual, incluyendo derechos de autor, patentes, marcas registradas y secretos comerciales, en el Sitio y su contenido son propiedad de la Empresa o de los proveedores de la Empresa. Tenga en cuenta que estas Condiciones y el acceso al Sitio no le otorgan ning\u00fan derecho, titularidad o inter\u00e9s sobre ning\u00fan derecho de propiedad intelectual, salvo los derechos de acceso limitados expresados en la Secci\u00f3n 2.1. La Empresa y sus proveedores se reservan todos los derechos no concedidos en las presentes Condiciones.<\/p>\n<h2>Enlaces y anuncios de terceros; otros usuarios<\/h2>\n<p>Enlaces y anuncios de terceros. El Sitio puede contener enlaces a sitios web y servicios de terceros y\/o mostrar anuncios de terceros. Dichos Enlaces y Anuncios de Terceros no est\u00e1n bajo el control de la Empresa, y la Empresa no es responsable de ning\u00fan Enlace y Anuncio de Terceros. La Empresa proporciona acceso a estos Enlaces y Anuncios de Terceros s\u00f3lo para su comodidad, y no revisa, aprueba, supervisa, respalda, garantiza ni hace ninguna declaraci\u00f3n con respecto a los Enlaces y Anuncios de Terceros. Usted utiliza todos los Enlaces y Anuncios de Terceros bajo su propio riesgo, y debe aplicar un nivel adecuado de precauci\u00f3n y discreci\u00f3n al hacerlo. Al hacer clic en cualquiera de los Enlaces y Anuncios de Terceros, se aplicar\u00e1n los t\u00e9rminos y pol\u00edticas del tercero en cuesti\u00f3n, incluidas las pr\u00e1cticas de privacidad y recopilaci\u00f3n de datos de dicho tercero.<\/p>\n<p>Otros usuarios. Cada usuario del Sitio es el \u00fanico responsable de todos y cada uno de sus propios Contenidos de Usuario. Dado que no controlamos el Contenido de Usuario, usted reconoce y acepta que no somos responsables de ning\u00fan Contenido de Usuario, ya sea proporcionado por usted o por otros. Usted acepta que la Empresa no ser\u00e1 responsable de ninguna p\u00e9rdida o da\u00f1o que se produzca como resultado de dichas interacciones. Si se produce una disputa entre usted y cualquier usuario del Sitio, no tenemos ninguna obligaci\u00f3n de involucrarnos.<\/p>\n<p>Por la presente, usted exime y libera para siempre a la Empresa y a nuestros directivos, empleados, agentes, sucesores y cesionarios de, y por la presente renuncia y renuncia a, todas y cada una de las disputas, reclamaciones, controversias, demandas, derechos, obligaciones, responsabilidades, acciones y causas de acci\u00f3n pasadas, presentes y futuras de cualquier tipo y naturaleza, que hayan surgido o surjan directa o indirectamente de, o que est\u00e9n relacionadas directa o indirectamente con, el Sitio. Si usted es residente de California, por la presente renuncia a la secci\u00f3n 1542 del c\u00f3digo civil de California en relaci\u00f3n con lo anterior, que establece: \"una exoneraci\u00f3n general no se extiende a reclamaciones que el acreedor no conozca o sospeche que existen a su favor en el momento de ejecutar la exoneraci\u00f3n, que de haber sido conocidas por \u00e9l habr\u00edan afectado materialmente a su acuerdo con el deudor\".<\/p>\n<p>Cookies y Web Beacons. Como cualquier otro sitio web, Caribbean Bariatric Institute utiliza \"cookies\". Estas cookies se utilizan para almacenar informaci\u00f3n, incluyendo las preferencias de los visitantes, y las p\u00e1ginas del sitio web que el visitante accedi\u00f3 o visit\u00f3. La informaci\u00f3n se utiliza para optimizar la experiencia de los usuarios mediante la personalizaci\u00f3n del contenido de nuestra p\u00e1gina web en funci\u00f3n del tipo de navegador de los visitantes y\/u otra informaci\u00f3n.<\/p>\n<h2>Descargo de responsabilidad<\/h2>\n<p>El sitio se proporciona \"tal cual\" y \"seg\u00fan disponibilidad\", y la empresa y sus proveedores renuncian expresamente a todas las garant\u00edas y condiciones de cualquier tipo, ya sean expresas, impl\u00edcitas o legales, incluidas todas las garant\u00edas o condiciones de comerciabilidad, idoneidad para un fin determinado, titularidad, disfrute tranquilo, precisi\u00f3n o no infracci\u00f3n. Nosotros y nuestros proveedores no garantizamos que el sitio satisfaga sus necesidades, est\u00e9 disponible de forma ininterrumpida, puntual, segura o libre de errores, ni que sea preciso, fiable, libre de virus u otros c\u00f3digos da\u00f1inos, completo, legal o seguro. Si la legislaci\u00f3n aplicable exige alguna garant\u00eda con respecto al sitio, todas esas garant\u00edas tienen una duraci\u00f3n limitada a noventa (90) d\u00edas a partir de la fecha del primer uso.<\/p>\n<p>Algunas jurisdicciones no permiten la exclusi\u00f3n de garant\u00edas impl\u00edcitas, por lo que es posible que la exclusi\u00f3n anterior no se aplique en su caso. Algunas jurisdicciones no permiten limitaciones sobre la duraci\u00f3n de una garant\u00eda impl\u00edcita, por lo que la limitaci\u00f3n anterior puede no ser aplicable en su caso.<\/p>\n<h2>Limitaci\u00f3n de responsabilidad<\/h2>\n<p>En la medida m\u00e1xima permitida por la ley, en ning\u00fan caso la empresa o nuestros proveedores ser\u00e1n responsables ante usted o ante terceros por lucro cesante, p\u00e9rdida de datos, costes de adquisici\u00f3n de productos sustitutivos, o cualquier da\u00f1o indirecto, consecuencial, ejemplar, incidental, especial o punitivo que surja de o est\u00e9 relacionado con estos t\u00e9rminos o con su uso o incapacidad para utilizar el sitio, incluso si la empresa ha sido advertida de la posibilidad de tales da\u00f1os. El acceso al sitio y su uso se realizan bajo su propia discreci\u00f3n y riesgo, y usted ser\u00e1 el \u00fanico responsable de cualquier da\u00f1o que se produzca en su dispositivo o sistema inform\u00e1tico, o de la p\u00e9rdida de datos que resulte de ello.<\/p>\n<p>En la m\u00e1xima medida permitida por la ley, y sin perjuicio de cualquier disposici\u00f3n en contrario contenida en el presente documento, nuestra responsabilidad frente a usted por cualquier da\u00f1o derivado o relacionado con este acuerdo, estar\u00e1 limitada en todo momento a un m\u00e1ximo de cincuenta d\u00f3lares estadounidenses (u.s. $50). La existencia de m\u00e1s de una reclamaci\u00f3n no ampliar\u00e1 este l\u00edmite. Usted acepta que nuestros proveedores no tendr\u00e1n ning\u00fan tipo de responsabilidad derivada de este acuerdo o relacionada con el mismo.<\/p>\n<p>Algunas jurisdicciones no permiten la limitaci\u00f3n o exclusi\u00f3n de responsabilidad por da\u00f1os incidentales o consecuentes, por lo que es posible que la limitaci\u00f3n o exclusi\u00f3n anterior no se aplique en su caso.<\/p>\n<p>Vigencia y terminaci\u00f3n. Con sujeci\u00f3n a lo dispuesto en esta Secci\u00f3n, estas Condiciones permanecer\u00e1n en pleno vigor y efecto mientras usted utilice el Sitio. Podremos suspender o rescindir sus derechos de uso del Sitio en cualquier momento y por cualquier motivo a nuestra entera discreci\u00f3n, incluido cualquier uso del Sitio que infrinja estas Condiciones. En caso de rescisi\u00f3n de sus derechos en virtud de las presentes Condiciones, su Cuenta y su derecho a acceder y utilizar el Sitio se rescindir\u00e1n inmediatamente. Usted entiende que cualquier rescisi\u00f3n de su Cuenta puede implicar la eliminaci\u00f3n de su Contenido de Usuario asociado a su Cuenta de nuestras bases de datos activas. La Empresa no tendr\u00e1 responsabilidad alguna frente a usted por la rescisi\u00f3n de sus derechos en virtud de las presentes Condiciones. Incluso despu\u00e9s de que se rescindan sus derechos en virtud de estas Condiciones, las siguientes disposiciones de estas Condiciones seguir\u00e1n en vigor: Secciones 2 a 2.5, Secci\u00f3n 3 y Secciones 4 a 10.<\/p>\n<h2>Pol\u00edtica de derechos de autor<\/h2>\n<p>La empresa respeta la propiedad intelectual de los dem\u00e1s y pide a los usuarios de nuestro sitio web que hagan lo mismo. En relaci\u00f3n con nuestro Sitio, hemos adoptado y aplicado una pol\u00edtica de respeto de la legislaci\u00f3n sobre derechos de autor que prev\u00e9 la retirada de cualquier material infractor y el cese de los usuarios de nuestro Sitio en l\u00ednea que infrinjan repetidamente los derechos de propiedad intelectual, incluidos los derechos de autor. Si cree que uno de nuestros usuarios, mediante el uso de nuestro Sitio, est\u00e1 infringiendo ilegalmente los derechos de autor de una obra, y desea que se retire el material supuestamente infractor, deber\u00e1 proporcionar la siguiente informaci\u00f3n en forma de notificaci\u00f3n escrita (de conformidad con 17 U.S.C. \u00a7 512(c)) a nuestro Agente de derechos de autor designado:<\/p>\n<p>su firma f\u00edsica o electr\u00f3nica;<br>identificaci\u00f3n de la(s) obra(s) protegida(s) por derechos de autor que usted afirma que ha(n) sido infringida(s);<br>identificaci\u00f3n del material de nuestros servicios que, seg\u00fan usted, infringe la ley y que solicita que retiremos;<br>informaci\u00f3n suficiente que nos permita localizar dicho material;<br>su direcci\u00f3n, n\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico;<br>una declaraci\u00f3n de que cree de buena fe que el uso del material censurable no est\u00e1 autorizado por el propietario de los derechos de autor, su agente o la ley; y<br>una declaraci\u00f3n de que la informaci\u00f3n contenida en la notificaci\u00f3n es exacta y, bajo pena de perjurio, que usted es el titular de los derechos de autor presuntamente infringidos o que est\u00e1 autorizado para actuar en nombre del titular de los derechos de autor.<br>Tenga en cuenta que, de conformidad con 17 U.S.C. \u00a7 512(f), cualquier tergiversaci\u00f3n de hechos materiales en una notificaci\u00f3n por escrito somete autom\u00e1ticamente a la parte reclamante a la responsabilidad por los da\u00f1os, costes y honorarios de abogados incurridos por nosotros en relaci\u00f3n con la notificaci\u00f3n por escrito y la alegaci\u00f3n de infracci\u00f3n de derechos de autor.<\/p>\n<h2>General<\/h2>\n<p>Estas Condiciones est\u00e1n sujetas a revisiones ocasionales, y si realizamos alg\u00fan cambio sustancial, podremos notific\u00e1rselo envi\u00e1ndole un correo electr\u00f3nico a la \u00faltima direcci\u00f3n de correo electr\u00f3nico que nos proporcion\u00f3 y\/o publicando de forma destacada un aviso de los cambios en nuestro Sitio. Usted es responsable de proporcionarnos su direcci\u00f3n de correo electr\u00f3nico m\u00e1s reciente. En caso de que la \u00faltima direcci\u00f3n de correo electr\u00f3nico que nos haya facilitado no sea v\u00e1lida, nuestro env\u00edo del correo electr\u00f3nico que contenga dicha notificaci\u00f3n constituir\u00e1, no obstante, una notificaci\u00f3n efectiva de los cambios descritos en la notificaci\u00f3n. Cualquier modificaci\u00f3n de las presentes Condiciones entrar\u00e1 en vigor en el plazo de treinta (30) d\u00edas naturales a partir de la fecha en que le hayamos enviado la notificaci\u00f3n por correo electr\u00f3nico o en el plazo de treinta (30) d\u00edas naturales a partir de la fecha en que hayamos publicado la notificaci\u00f3n de las modificaciones en nuestro Sitio. Estos cambios entrar\u00e1n en vigor inmediatamente para los nuevos usuarios de nuestro Sitio. El uso continuado de nuestro Sitio despu\u00e9s de la notificaci\u00f3n de dichos cambios indicar\u00e1 su reconocimiento de dichos cambios y su acuerdo a estar obligado por los t\u00e9rminos y condiciones de dichos cambios. Resoluci\u00f3n de conflictos. Lea atentamente el presente Acuerdo de Arbitraje. Forma parte de su contrato con la Empresa y afecta a sus derechos. Contiene procedimientos de ARBITRAJE OBLIGATORIO Y VINCULANTE Y UNA RENUNCIA A LA PRESENTACI\u00d3N DE ACCIONES COLECTIVAS.<\/p>\n<p>Aplicabilidad del acuerdo de arbitraje. Todas las reclamaciones y disputas relacionadas con las Condiciones o el uso de cualquier producto o servicio proporcionado por la Empresa que no puedan resolverse de manera informal o en un tribunal de escasa cuant\u00eda se resolver\u00e1n mediante arbitraje vinculante de manera individual seg\u00fan los t\u00e9rminos de este Acuerdo de Arbitraje. Salvo acuerdo en contrario, todos los procedimientos de arbitraje se celebrar\u00e1n en ingl\u00e9s. El presente Acuerdo de Arbitraje se aplica a usted y a la Empresa, as\u00ed como a sus filiales, afiliados, agentes, empleados, predecesores en inter\u00e9s, sucesores y cesionarios, as\u00ed como a todos los usuarios o beneficiarios autorizados o no autorizados de los servicios o bienes proporcionados en virtud de las Condiciones.<\/p>\n<p>Requisito de notificaci\u00f3n y resoluci\u00f3n informal de conflictos. Antes de que cualquiera de las partes pueda recurrir al arbitraje, deber\u00e1 enviar a la otra parte una Notificaci\u00f3n de litigio por escrito en la que describa la naturaleza y el fundamento de la reclamaci\u00f3n o litigio, as\u00ed como la reparaci\u00f3n solicitada. La Notificaci\u00f3n a la Compa\u00f1\u00eda debe enviarse a: 100 Main Street. Una vez recibida la notificaci\u00f3n, usted y la empresa pueden intentar resolver la reclamaci\u00f3n o disputa de manera informal. Si usted y la Compa\u00f1\u00eda no resuelven la reclamaci\u00f3n o disputa en un plazo de treinta (30) d\u00edas tras la recepci\u00f3n de la Notificaci\u00f3n, cualquiera de las partes podr\u00e1 iniciar un procedimiento de arbitraje. El importe de cualquier oferta de acuerdo realizada por cualquiera de las partes no podr\u00e1 revelarse al \u00e1rbitro hasta que \u00e9ste haya determinado el importe del laudo al que tiene derecho cualquiera de las partes.<\/p>\n<p>Reglas de arbitraje. El arbitraje se iniciar\u00e1 a trav\u00e9s de la Asociaci\u00f3n Americana de Arbitraje (AAA), un proveedor establecido de resoluci\u00f3n alternativa de conflictos que ofrece arbitraje seg\u00fan lo establecido en esta secci\u00f3n. Si la AAA no est\u00e1 disponible para arbitrar, las partes acordar\u00e1n seleccionar un Proveedor alternativo de ADR. Las normas del Proveedor de ADR regir\u00e1n todos los aspectos del arbitraje, excepto en la medida en que dichas normas entren en conflicto con las Condiciones. Las Normas de Arbitraje de Consumo de la AAA que rigen el arbitraje est\u00e1n disponibles en l\u00ednea en adr.org o llamando a la AAA al 1-800-778-7879. El arbitraje ser\u00e1 dirigido por un \u00e1rbitro \u00fanico y neutral. Las reclamaciones o litigios cuyo importe total sea inferior a diez mil d\u00f3lares estadounidenses (US $10.000,00) podr\u00e1n resolverse mediante arbitraje vinculante sin comparecencia, a elecci\u00f3n de la parte que solicite la reparaci\u00f3n. En el caso de reclamaciones o litigios cuyo importe total sea igual o superior a diez mil d\u00f3lares estadounidenses ($10.000,00), el derecho a una audiencia se regir\u00e1 por el Reglamento de Arbitraje. Toda audiencia se celebrar\u00e1 en un lugar situado a menos de 100 millas de su residencia, a menos que usted resida fuera de los Estados Unidos, y a menos que las partes acuerden otra cosa. Si usted reside fuera de Estados Unidos, el \u00e1rbitro notificar\u00e1 a las partes con antelaci\u00f3n razonable la fecha, hora y lugar de cualquier audiencia oral. Cualquier sentencia sobre el laudo dictado por el \u00e1rbitro podr\u00e1 ser presentada ante cualquier tribunal de jurisdicci\u00f3n competente. Si el \u00e1rbitro le concede un laudo que sea superior a la \u00faltima oferta de acuerdo que la Compa\u00f1\u00eda le hizo antes del inicio del arbitraje, la Compa\u00f1\u00eda le pagar\u00e1 a usted el importe mayor entre el laudo y $2.500,00. Cada parte correr\u00e1 con sus propios gastos y desembolsos derivados del arbitraje y pagar\u00e1 una parte igual de los honorarios y gastos del Proveedor de ADR.<\/p>\n<p>Reglas adicionales para el arbitraje sin comparecencia. Si se elige el arbitraje sin comparecencia, el arbitraje se llevar\u00e1 a cabo por tel\u00e9fono, en l\u00ednea y\/o se basar\u00e1 \u00fanicamente en presentaciones escritas; la parte que inicie el arbitraje elegir\u00e1 la forma espec\u00edfica. El arbitraje no implicar\u00e1 la comparecencia personal de las partes ni de los testigos, a menos que las partes acuerden lo contrario.<\/p>\n<p>Plazos. Si usted o la Empresa recurren al arbitraje, la acci\u00f3n de arbitraje debe iniciarse y\/o exigirse dentro del plazo de prescripci\u00f3n y dentro de cualquier plazo impuesto en virtud de las Normas de la AAA para la reclamaci\u00f3n pertinente.<\/p>\n<p>Autoridad del \u00e1rbitro. Si se inicia el arbitraje, el \u00e1rbitro decidir\u00e1 los derechos y responsabilidades de usted y de la Empresa, y la disputa no se consolidar\u00e1 con ning\u00fan otro asunto ni se unir\u00e1 a otros casos o partes. El \u00e1rbitro tendr\u00e1 autoridad para conceder mociones dispositivas sobre la totalidad o parte de cualquier reclamaci\u00f3n. El \u00e1rbitro estar\u00e1 facultado para conceder indemnizaciones pecuniarias y para conceder cualquier reparaci\u00f3n o compensaci\u00f3n no pecuniaria disponible para un individuo en virtud de la legislaci\u00f3n aplicable, las Normas de la AAA y las Condiciones. El \u00e1rbitro emitir\u00e1 un laudo y una declaraci\u00f3n de decisi\u00f3n por escrito en los que se describir\u00e1n los resultados y conclusiones esenciales en los que se basa el laudo. El \u00e1rbitro tiene la misma autoridad para conceder indemnizaciones a t\u00edtulo individual que la que tendr\u00eda un juez en un tribunal de justicia. El laudo del \u00e1rbitro es definitivo y vinculante para usted y la empresa.<\/p>\n<p>Renuncia a juicio por jurado. LAS PARTES RENUNCIAN POR LA PRESENTE A SUS DERECHOS CONSTITUCIONALES Y ESTATUTARIOS DE IR A LOS TRIBUNALES Y TENER UN JUICIO ANTE UN JUEZ O UN JURADO, optando en su lugar por que todas las reclamaciones y disputas se resuelvan mediante arbitraje en virtud del presente Acuerdo de Arbitraje. Los procedimientos de arbitraje suelen ser m\u00e1s limitados, m\u00e1s eficaces y menos costosos que las normas aplicables en un tribunal y est\u00e1n sujetos a una revisi\u00f3n muy limitada por parte de un tribunal. En caso de que surja cualquier litigio entre usted y la Empresa en cualquier tribunal estatal o federal en una demanda para anular o hacer cumplir un laudo arbitral o de otro tipo, USTED Y LA EMPRESA RENUNCIAN A TODOS LOS DERECHOS A UN JUICIO CON JURADO, eligiendo en su lugar que la disputa sea resuelta por un juez.<\/p>\n<p>Renuncia a acciones colectivas o consolidadas. Todas las reclamaciones y disputas dentro del \u00e1mbito de este acuerdo de arbitraje deben ser arbitradas o litigadas de forma individual y no colectiva, y las reclamaciones de m\u00e1s de un cliente o usuario no pueden ser arbitradas o litigadas de forma conjunta o consolidada con las de cualquier otro cliente o usuario.<\/p>\n<p>Confidencialidad. Todos los aspectos del procedimiento de arbitraje ser\u00e1n estrictamente confidenciales. Las partes acuerdan mantener la confidencialidad a menos que la ley exija lo contrario. Este p\u00e1rrafo no impedir\u00e1 que una de las partes presente ante un tribunal de justicia cualquier informaci\u00f3n necesaria para hacer cumplir este Acuerdo, para hacer cumplir un laudo arbitral o para solicitar medidas cautelares o equitativas.<\/p>\n<p>Divisibilidad. Si un tribunal de jurisdicci\u00f3n competente considera que alguna parte o partes del presente Acuerdo de Arbitraje son inv\u00e1lidas o inejecutables en virtud de la ley, dicha parte o partes espec\u00edficas carecer\u00e1n de fuerza y efecto y se separar\u00e1n, y el resto del Acuerdo continuar\u00e1 en pleno vigor y efecto.<\/p>\n<p>Derecho de renuncia. Cualquiera o todos los derechos y limitaciones establecidos en este Acuerdo de Arbitraje pueden ser renunciados por la parte contra la que se hace valer la reclamaci\u00f3n. Dicha renuncia no eximir\u00e1 ni afectar\u00e1 a ninguna otra parte del presente Acuerdo de Arbitraje.<\/p>\n<p>Supervivencia del Acuerdo. El presente Acuerdo de Arbitraje sobrevivir\u00e1 a la terminaci\u00f3n de su relaci\u00f3n con la Empresa.<\/p>\n<p>Tribunal de Reclamaciones de Menor Cuant\u00eda. No obstante lo anterior, tanto usted como la empresa podr\u00e1n interponer una demanda individual ante un tribunal de escasa cuant\u00eda.<\/p>\n<p>Reparaci\u00f3n equitativa de emergencia. No obstante lo anterior, cualquiera de las partes podr\u00e1 solicitar medidas equitativas de emergencia ante un tribunal estatal o federal con el fin de mantener el statu quo en espera del arbitraje. La solicitud de medidas cautelares no se considerar\u00e1 una renuncia a ning\u00fan otro derecho u obligaci\u00f3n en virtud del presente Acuerdo de Arbitraje.<\/p>\n<p>Reclamaciones no sujetas a arbitraje. No obstante lo anterior, las reclamaciones por difamaci\u00f3n, violaci\u00f3n de la Ley de Fraude y Abuso Inform\u00e1tico, e infracci\u00f3n o apropiaci\u00f3n indebida de patentes, derechos de autor, marcas comerciales o secretos comerciales de la otra parte no estar\u00e1n sujetas al presente Acuerdo de Arbitraje.<\/p>\n<p>En cualquier circunstancia en la que el anterior Acuerdo de Arbitraje permita a las partes litigar ante un tribunal, las partes acuerdan por la presente someterse a la jurisdicci\u00f3n personal de los tribunales situados en el Condado de Netherlands, California, a tales efectos.<\/p>\n<p>El Sitio puede estar sujeto a las leyes de control de exportaciones de Estados Unidos y puede estar sujeto a las regulaciones de exportaci\u00f3n o importaci\u00f3n de otros pa\u00edses. Usted se compromete a no exportar, reexportar o transferir, directa o indirectamente, ning\u00fan dato t\u00e9cnico estadounidense adquirido de la Empresa, ni ning\u00fan producto que utilice dichos datos, infringiendo las leyes o normativas de exportaci\u00f3n de Estados Unidos.<\/p>\n<p>La empresa se encuentra en la direcci\u00f3n indicada en el apartado 10.8. Si reside en California, puede presentar sus quejas ante la Unidad de Asistencia para Quejas de la Divisi\u00f3n de Productos de Consumo del Departamento de Asuntos del Consumidor de California, poni\u00e9ndose en contacto con ellos por escrito en 400 R Street, Sacramento, CA 95814, o por tel\u00e9fono en el (800) 952-5210.<\/p>\n<p>Comunicaciones electr\u00f3nicas. Las comunicaciones entre usted y la Empresa utilizan medios electr\u00f3nicos, tanto si usted utiliza el Sitio como si nos env\u00eda correos electr\u00f3nicos, o si la Empresa publica avisos en el Sitio o se comunica con usted por correo electr\u00f3nico. A efectos contractuales, usted (a) da su consentimiento para recibir comunicaciones de la Empresa de forma electr\u00f3nica; y (b) acepta que todos los t\u00e9rminos y condiciones, acuerdos, avisos, divulgaciones y otras comunicaciones que la Empresa le proporcione de forma electr\u00f3nica satisfacen cualquier obligaci\u00f3n legal que dichas comunicaciones satisfacer\u00edan si estuvieran por escrito en papel.<\/p>\n<p>Condiciones completas. Estas Condiciones constituyen el acuerdo completo entre usted y nosotros en relaci\u00f3n con el uso del Sitio. El hecho de que no ejerzamos o hagamos valer cualquier derecho o disposici\u00f3n de estas Condiciones no supondr\u00e1 una renuncia a dicho derecho o disposici\u00f3n. Los t\u00edtulos de las secciones de estas Condiciones son meramente indicativos y carecen de efectos legales o contractuales. La palabra \"incluido\" significa \"incluido sin limitaci\u00f3n\". Si alguna disposici\u00f3n de estas Condiciones se considera inv\u00e1lida o inaplicable, las dem\u00e1s disposiciones de estas Condiciones no se ver\u00e1n afectadas y la disposici\u00f3n inv\u00e1lida o inaplicable se considerar\u00e1 modificada para que sea v\u00e1lida y aplicable en la m\u00e1xima medida permitida por la ley. Su relaci\u00f3n con la Empresa es la de un contratista independiente, y ninguna de las partes es agente o socio de la otra. Usted no podr\u00e1 ceder, subcontratar, delegar ni transferir de ning\u00fan otro modo las presentes Condiciones ni sus derechos y obligaciones sin el consentimiento previo por escrito de la Empresa, y cualquier intento de cesi\u00f3n, subcontrataci\u00f3n, delegaci\u00f3n o transferencia que infrinja lo anterior ser\u00e1 nulo y sin efecto. La Empresa podr\u00e1 ceder libremente las presentes Condiciones. Los t\u00e9rminos y condiciones establecidos en estas Condiciones ser\u00e1n vinculantes para los cesionarios.<\/p>\n<p>Su privacidad. Lea nuestra Pol\u00edtica de privacidad.<\/p>\n<p>Informaci\u00f3n sobre derechos de autor\/marcas registradas. Copyright \u00a9. Todos los derechos reservados. Todas las marcas comerciales, logotipos y marcas de servicio que aparecen en el Sitio son propiedad nuestra o de terceros. Usted no est\u00e1 autorizado a utilizar estas Marcas sin nuestro consentimiento previo por escrito o el consentimiento del tercero que pueda ser propietario de las Marcas.<\/p>\n<h2>Informaci\u00f3n de contacto<\/h2>\n<p>Direcci\u00f3n: Avenida Luis Mu\u00f1oz Mar\u00edn, 100<br>Caguas, 00725, Puerto Rico<\/p>\n<p>Correo electr\u00f3nico: info@caribbeanbariatric.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Website Terms of Use The Caribbean Bariatric Institute website located at caribbeanbariatric.com is a copyrighted work belonging to Caribbean Bariatric Institute. Certain features of the Site may be subject to additional guidelines, terms, or rules, which will be posted on the Site in connection with such features. All such additional terms, guidelines, and rules are [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3151","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms of Use &#8211; Caribbean Bariatric Institute<\/title>\n<meta name=\"description\" content=\"Explore the Terms of Use for Caribbean Bariatric Institute, covering site access, cookies, third-party links, intellectual property, and dispute resolution.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caribbeanbariatric.com\/es\/terms-of-use\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms of Use &#8211; Caribbean Bariatric Institute\" \/>\n<meta property=\"og:description\" content=\"Explore the Terms of Use for Caribbean Bariatric Institute, covering site access, cookies, third-party links, intellectual property, and dispute resolution.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caribbeanbariatric.com\/es\/terms-of-use\/\" \/>\n<meta property=\"og:site_name\" content=\"Caribbean Bariatric Institute\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T17:49:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/terms-of-use\\\/\",\"url\":\"https:\\\/\\\/caribbeanbariatric.com\\\/terms-of-use\\\/\",\"name\":\"Terms of Use &#8211; Caribbean Bariatric Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#website\"},\"datePublished\":\"2022-02-03T17:10:03+00:00\",\"dateModified\":\"2024-10-03T17:49:30+00:00\",\"description\":\"Explore the Terms of Use for Caribbean Bariatric Institute, covering site access, cookies, third-party links, intellectual property, and dispute resolution.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/terms-of-use\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/caribbeanbariatric.com\\\/terms-of-use\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/terms-of-use\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/caribbeanbariatric.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of Use\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#website\",\"url\":\"https:\\\/\\\/caribbeanbariatric.com\\\/\",\"name\":\"Caribbean Bariatric Institute\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/caribbeanbariatric.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#organization\",\"name\":\"Caribbean Bariatric Institute\",\"url\":\"https:\\\/\\\/caribbeanbariatric.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/caribbeanbariatric.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CBI_Logo_Horiz_Blue_Gray.jpg\",\"contentUrl\":\"https:\\\/\\\/caribbeanbariatric.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CBI_Logo_Horiz_Blue_Gray.jpg\",\"width\":1347,\"height\":390,\"caption\":\"Caribbean Bariatric Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/caribbeanbariatric.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos de Uso \u2013 Caribbean Bariatric Institute","description":"Explore los T\u00e9rminos de Uso del Caribbean Bariatric Institute, que cubren el acceso al sitio, cookies, enlaces de terceros, propiedad intelectual y resoluci\u00f3n de disputas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caribbeanbariatric.com\/es\/terms-of-use\/","og_locale":"es_ES","og_type":"article","og_title":"Terms of Use &#8211; Caribbean Bariatric Institute","og_description":"Explore the Terms of Use for Caribbean Bariatric Institute, covering site access, cookies, third-party links, intellectual property, and dispute resolution.","og_url":"https:\/\/caribbeanbariatric.com\/es\/terms-of-use\/","og_site_name":"Caribbean Bariatric Institute","article_modified_time":"2024-10-03T17:49:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/caribbeanbariatric.com\/terms-of-use\/","url":"https:\/\/caribbeanbariatric.com\/terms-of-use\/","name":"T\u00e9rminos de Uso \u2013 Caribbean Bariatric Institute","isPartOf":{"@id":"https:\/\/caribbeanbariatric.com\/#website"},"datePublished":"2022-02-03T17:10:03+00:00","dateModified":"2024-10-03T17:49:30+00:00","description":"Explore los T\u00e9rminos de Uso del Caribbean Bariatric Institute, que cubren el acceso al sitio, cookies, enlaces de terceros, propiedad intelectual y resoluci\u00f3n de disputas.","breadcrumb":{"@id":"https:\/\/caribbeanbariatric.com\/terms-of-use\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caribbeanbariatric.com\/terms-of-use\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/caribbeanbariatric.com\/terms-of-use\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/caribbeanbariatric.com\/"},{"@type":"ListItem","position":2,"name":"Terms of Use"}]},{"@type":"WebSite","@id":"https:\/\/caribbeanbariatric.com\/#website","url":"https:\/\/caribbeanbariatric.com\/","name":"Instituto Bari\u00e1trico del Caribe","description":"","publisher":{"@id":"https:\/\/caribbeanbariatric.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caribbeanbariatric.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/caribbeanbariatric.com\/#organization","name":"Instituto Bari\u00e1trico del Caribe","url":"https:\/\/caribbeanbariatric.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/caribbeanbariatric.com\/#\/schema\/logo\/image\/","url":"https:\/\/caribbeanbariatric.com\/wp-content\/uploads\/2024\/10\/CBI_Logo_Horiz_Blue_Gray.jpg","contentUrl":"https:\/\/caribbeanbariatric.com\/wp-content\/uploads\/2024\/10\/CBI_Logo_Horiz_Blue_Gray.jpg","width":1347,"height":390,"caption":"Caribbean Bariatric Institute"},"image":{"@id":"https:\/\/caribbeanbariatric.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/pages\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":0,"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/pages\/3151\/revisions"}],"wp:attachment":[{"href":"https:\/\/caribbeanbariatric.com\/es\/wp-json\/wp\/v2\/media?parent=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}